{"id":1330,"date":"2024-05-20T09:46:24","date_gmt":"2024-05-20T07:46:24","guid":{"rendered":"https:\/\/greenfilmforum.eu\/mallorca-acogera-el-primer-green-film-forum-en-octubre-de-2024\/"},"modified":"2024-10-16T16:39:01","modified_gmt":"2024-10-16T14:39:01","slug":"mallorca-acogera-el-primer-green-film-forum-en-octubre-de-2024","status":"publish","type":"post","link":"https:\/\/greenfilmforum.eu\/es\/mallorca-acogera-el-primer-green-film-forum-en-octubre-de-2024\/","title":{"rendered":"Mallorca acoger\u00e1 el primer Green Film Forum en octubre de 2024"},"content":{"rendered":"\n<p>Green Film Forum (GFF) est\u00e1 llamado a convertirse en un punto de encuentro internacional de conocimientos, experiencias y pr\u00e1cticas sostenibles en la industria audiovisual. Este foro contribuir\u00e1 de manera significativa a posicionar a Mallorca y el trabajo de la film commission insular como un referente global en el campo. El evento se celebrar\u00e1 en Palma (Mallorca) los d\u00edas 18, 19 y 20 de octubre de 2024. <\/p>\n\n<p>Green Film Forum es una iniciativa del Consell Insular de Mallorca a trav\u00e9s de la Fundaci\u00f3 Mallorca Turisme, y cuenta con financiaci\u00f3n europea del plan NextGenerationEU. Entre otros temas, los participantes tendr\u00e1n la oportunidad de conocer las nuevas tendencias para lograr producciones sostenibles, incluyendo soluciones para el suministro energ\u00e9tico y el transporte, la adaptaci\u00f3n del dise\u00f1o de producci\u00f3n y la formaci\u00f3n. <\/p>\n\n<p>La innovaci\u00f3n ser\u00e1 un aspecto clave del programa, y se abordar\u00e1 c\u00f3mo puede ayudar a que el cine sea m\u00e1s ecol\u00f3gico, no solo mediante avances tecnol\u00f3gicos, sino tambi\u00e9n a trav\u00e9s de nuevas formas de producci\u00f3n, como la producci\u00f3n virtual.<\/p>\n\n<p>Se analizar\u00e1n diferentes modelos de certificaci\u00f3n y protocolos verdes en varios territorios mediante estudios de caso, as\u00ed como los avances hacia la creaci\u00f3n de directrices comunes y un est\u00e1ndar europeo. Adem\u00e1s, se tratar\u00e1 la integraci\u00f3n de la sostenibilidad en la narrativa y su papel en la creaci\u00f3n de contenidos. <\/p>\n\n<p>Green Film Forum se presentar\u00e1 el s\u00e1bado 18 de mayo en el Festival de Cine de Cannes, durante una sesi\u00f3n exclusiva de networking organizada por Screen International en colaboraci\u00f3n con la Mallorca Film Commission, donde 40 profesionales del sector est\u00e1n invitados a debatir posibles colaboraciones y lo que Mallorca puede aportar a la industria cinematogr\u00e1fica.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Green Film Forum se presentar\u00e1 el s\u00e1bado 18 de mayo en el Festival de Cine de Cannes<\/p>\n","protected":false},"author":1,"featured_media":1222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"_links":{"self":[{"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/posts\/1330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/comments?post=1330"}],"version-history":[{"count":1,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/posts\/1330\/revisions"}],"predecessor-version":[{"id":1331,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/posts\/1330\/revisions\/1331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/media\/1222"}],"wp:attachment":[{"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/media?parent=1330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/categories?post=1330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/greenfilmforum.eu\/es\/wp-json\/wp\/v2\/tags?post=1330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}